{"id":6550,"date":"2021-05-31T13:39:03","date_gmt":"2021-05-31T17:39:03","guid":{"rendered":"https:\/\/rdeecanada.flywheelstaging.com\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/"},"modified":"2021-05-31T13:39:05","modified_gmt":"2021-05-31T17:39:05","slug":"sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada","status":"publish","type":"nouvelles","link":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/","title":{"rendered":"Sondage pour les propri\u00e9taires d&#8217;entreprises touristiques francophones au Canada!"},"content":{"rendered":"<p>Ce sondage a pour objectif d&#8217;\u00e9valuer l&#8217;\u00e9volution de l&#8217;offre touristique francophone ou bilingue au Canada pr\u00e8s de 13 mois apr\u00e8s le d\u00e9but de la pand\u00e9mie. Les r\u00e9ponses obtenues permettront de mieux\u00a0cibler les besoins des entreprises et bien promouvoir l&#8217;offre touristique pour la saison 2021.<\/p>\n<p>Vous pouvez r\u00e9pondre au sondage en <a href=\"https:\/\/fr.surveymonkey.com\/r\/8VN5MM3\">fran\u00e7ais<\/a> ou en <a href=\"https:\/\/fr.surveymonkey.com\/r\/8GPJ9FT\">anglais<\/a>!<\/p>\n","protected":false},"parent":0,"template":"","categorie-de-nouvelle":[],"class_list":["post-6550","nouvelles","type-nouvelles","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sondage pour les propri\u00e9taires d&#039;entreprises touristiques francophones au Canada! - RD\u00c9E Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sondage pour les propri\u00e9taires d&#039;entreprises touristiques francophones au Canada! - RD\u00c9E Canada\" \/>\n<meta property=\"og:description\" content=\"Ce sondage a pour objectif d&#8217;\u00e9valuer l&#8217;\u00e9volution de l&#8217;offre touristique francophone ou bilingue au Canada pr\u00e8s de 13 mois apr\u00e8s le d\u00e9but de la pand\u00e9mie. Les r\u00e9ponses obtenues permettront de mieux\u00a0cibler les besoins des entreprises et bien promouvoir l&#8217;offre touristique pour la saison 2021. Vous pouvez r\u00e9pondre au sondage en fran\u00e7ais ou en anglais!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"RD\u00c9E Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-31T17:39:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/\",\"url\":\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/\",\"name\":\"Sondage pour les propri\u00e9taires d'entreprises touristiques francophones au Canada! - RD\u00c9E Canada\",\"isPartOf\":{\"@id\":\"https:\/\/rdee.ca\/#website\"},\"datePublished\":\"2021-05-31T17:39:03+00:00\",\"dateModified\":\"2021-05-31T17:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/rdee.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\/\/rdee.ca\/nouvelles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sondage pour les propri\u00e9taires d&#8217;entreprises touristiques francophones au Canada!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rdee.ca\/#website\",\"url\":\"https:\/\/rdee.ca\/\",\"name\":\"RD\u00c9E Canada\",\"description\":\"Le leader du d\u00e9veloppement \u00e9conomique des communaut\u00e9s francophones et acadienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rdee.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sondage pour les propri\u00e9taires d'entreprises touristiques francophones au Canada! - RD\u00c9E Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/","og_locale":"en_US","og_type":"article","og_title":"Sondage pour les propri\u00e9taires d'entreprises touristiques francophones au Canada! - RD\u00c9E Canada","og_description":"Ce sondage a pour objectif d&#8217;\u00e9valuer l&#8217;\u00e9volution de l&#8217;offre touristique francophone ou bilingue au Canada pr\u00e8s de 13 mois apr\u00e8s le d\u00e9but de la pand\u00e9mie. Les r\u00e9ponses obtenues permettront de mieux\u00a0cibler les besoins des entreprises et bien promouvoir l&#8217;offre touristique pour la saison 2021. Vous pouvez r\u00e9pondre au sondage en fran\u00e7ais ou en anglais!","og_url":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/","og_site_name":"RD\u00c9E Canada","article_modified_time":"2021-05-31T17:39:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/","url":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/","name":"Sondage pour les propri\u00e9taires d'entreprises touristiques francophones au Canada! - RD\u00c9E Canada","isPartOf":{"@id":"https:\/\/rdee.ca\/#website"},"datePublished":"2021-05-31T17:39:03+00:00","dateModified":"2021-05-31T17:39:05+00:00","breadcrumb":{"@id":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rdee.ca\/en\/nouvelles\/sondage-pour-les-proprietaires-dentreprises-touristiques-francophones-au-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rdee.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/rdee.ca\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"Sondage pour les propri\u00e9taires d&#8217;entreprises touristiques francophones au Canada!"}]},{"@type":"WebSite","@id":"https:\/\/rdee.ca\/#website","url":"https:\/\/rdee.ca\/","name":"RD\u00c9E Canada","description":"Le leader du d\u00e9veloppement \u00e9conomique des communaut\u00e9s francophones et acadienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdee.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles\/6550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"version-history":[{"count":0,"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles\/6550\/revisions"}],"wp:attachment":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/media?parent=6550"}],"wp:term":[{"taxonomy":"categorie-de-nouvelle","embeddable":true,"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/categorie-de-nouvelle?post=6550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}