{"id":3908,"date":"2020-04-02T10:40:35","date_gmt":"2020-04-02T14:40:35","guid":{"rendered":"http:\/\/staging.rdeecanada.flywheelsites.com\/nouvelles\/restons-en-contact\/"},"modified":"2020-04-02T10:40:35","modified_gmt":"2020-04-02T14:40:35","slug":"restons-en-contact","status":"publish","type":"nouvelles","link":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/","title":{"rendered":"Restons en contact !"},"content":{"rendered":"<p>Envie d\u2019en savoir plus sur les actions du R\u00e9seau de d\u00e9veloppement \u00e9conomique et d\u2019employabilit\u00e9 (RD\u00c9E Canada), de d\u00e9couvrir nos enjeux et nos r\u00e9ponses \u00e0 vos pr\u00e9occupations ?<\/p>\n<p>Abonnez-vous notre\u00a0<a href=\"https:\/\/rdee.us8.list-manage.com\/subscribe?u=9f887f619fa8494059e678e29&amp;id=4992624f0c\">bulletin d\u2019information bimensuel<\/a>\u00a0pour recevoir les nouvelles importantes du RD\u00c9E Canada, de ses membres du R\u00e9seau national et de la francophonie \u00e9conomique canadienne.<\/p>\n<p>\u2014<\/p>\n<p>Le R\u00e9seau de d\u00e9veloppement \u00e9conomique et d\u2019employabilit\u00e9 (RD\u00c9E Canada) \u0153uvre depuis plus de 20 ans \u00e0 favoriser le d\u00e9veloppement \u00e9conomique des communaut\u00e9s francophones et acadienne en appuyant les actions collectives de ses membres et en assurant un leadership national bas\u00e9 sur la collaboration et les partenariats.<\/p>\n","protected":false},"parent":0,"template":"","categorie-de-nouvelle":[64],"class_list":["post-3908","nouvelles","type-nouvelles","status-publish","hentry","categorie-de-nouvelle-tourism"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Restons en contact ! - RD\u00c9E Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restons en contact ! - RD\u00c9E Canada\" \/>\n<meta property=\"og:description\" content=\"Envie d\u2019en savoir plus sur les actions du R\u00e9seau de d\u00e9veloppement \u00e9conomique et d\u2019employabilit\u00e9 (RD\u00c9E Canada), de d\u00e9couvrir nos enjeux et nos r\u00e9ponses \u00e0 vos pr\u00e9occupations ? Abonnez-vous notre\u00a0bulletin d\u2019information bimensuel\u00a0pour recevoir les nouvelles importantes du RD\u00c9E Canada, de ses membres du R\u00e9seau national et de la francophonie \u00e9conomique canadienne. \u2014 Le R\u00e9seau de d\u00e9veloppement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/\" \/>\n<meta property=\"og:site_name\" content=\"RD\u00c9E Canada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/\",\"url\":\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/\",\"name\":\"Restons en contact ! - RD\u00c9E Canada\",\"isPartOf\":{\"@id\":\"https:\/\/rdee.ca\/#website\"},\"datePublished\":\"2020-04-02T14:40:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/rdee.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\/\/rdee.ca\/nouvelles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restons en contact !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rdee.ca\/#website\",\"url\":\"https:\/\/rdee.ca\/\",\"name\":\"RD\u00c9E Canada\",\"description\":\"Le leader du d\u00e9veloppement \u00e9conomique des communaut\u00e9s francophones et acadienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rdee.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restons en contact ! - RD\u00c9E Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/","og_locale":"en_US","og_type":"article","og_title":"Restons en contact ! - RD\u00c9E Canada","og_description":"Envie d\u2019en savoir plus sur les actions du R\u00e9seau de d\u00e9veloppement \u00e9conomique et d\u2019employabilit\u00e9 (RD\u00c9E Canada), de d\u00e9couvrir nos enjeux et nos r\u00e9ponses \u00e0 vos pr\u00e9occupations ? Abonnez-vous notre\u00a0bulletin d\u2019information bimensuel\u00a0pour recevoir les nouvelles importantes du RD\u00c9E Canada, de ses membres du R\u00e9seau national et de la francophonie \u00e9conomique canadienne. \u2014 Le R\u00e9seau de d\u00e9veloppement [&hellip;]","og_url":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/","og_site_name":"RD\u00c9E Canada","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/","url":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/","name":"Restons en contact ! - RD\u00c9E Canada","isPartOf":{"@id":"https:\/\/rdee.ca\/#website"},"datePublished":"2020-04-02T14:40:35+00:00","breadcrumb":{"@id":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rdee.ca\/en\/nouvelles\/restons-en-contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rdee.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/rdee.ca\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"Restons en contact !"}]},{"@type":"WebSite","@id":"https:\/\/rdee.ca\/#website","url":"https:\/\/rdee.ca\/","name":"RD\u00c9E Canada","description":"Le leader du d\u00e9veloppement \u00e9conomique des communaut\u00e9s francophones et acadienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdee.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles\/3908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles"}],"about":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/types\/nouvelles"}],"version-history":[{"count":0,"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/nouvelles\/3908\/revisions"}],"wp:attachment":[{"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/media?parent=3908"}],"wp:term":[{"taxonomy":"categorie-de-nouvelle","embeddable":true,"href":"https:\/\/rdee.ca\/en\/wp-json\/wp\/v2\/categorie-de-nouvelle?post=3908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}